{"id":156,"count":2,"description":"","link":"https:\/\/www.oeffentlichkeitsgesetz.ch\/francais\/tag\/ethz\/","name":"ETHZ","slug":"ethz","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/francais\/wp-json\/wp\/v2\/tags\/156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/francais\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/francais\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/francais\/wp-json\/wp\/v2\/posts?tags=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}