{"id":12856,"date":"2021-02-23T08:00:21","date_gmt":"2021-02-23T07:00:21","guid":{"rendered":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/?p=12856"},"modified":"2021-02-23T21:34:23","modified_gmt":"2021-02-23T20:34:23","slug":"die-wochenzeitung-gewinnt-den-prix-transparence-2020","status":"publish","type":"post","link":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/2021\/02\/die-wochenzeitung-gewinnt-den-prix-transparence-2020\/","title":{"rendered":"Die Wochenzeitung gewinnt den Prix Transparence 2020"},"content":{"rendered":"<div id=\"attachment_12890\" class=\"wp-caption alignnone\" style=\"width: 592px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12890 size-full\" src=\"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/files\/2021\/02\/Foto-Web-2_sw.jpg\" alt=\"\" width=\"582\" height=\"327\" srcset=\"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/files\/2021\/02\/Foto-Web-2_sw.jpg 582w, https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/files\/2021\/02\/Foto-Web-2_sw-300x169.jpg 300w\" sizes=\"auto, (max-width: 582px) 100vw, 582px\" \/> \u00abIst von \u00f6ffentlichem Interesse\u00bb: Die WOZ-Journalisten Surber und Jir\u00e1t.<p class=\"wp-caption-text\"><\/p><\/div>\n<p><em>Von Martin Stoll.<\/em> <strong>F\u00fcnf Jahre lang k\u00e4mpften sie f\u00fcr die Daten, die schliesslich einen tiefen Einblick ins Schweizer R\u00fcstungsgesch\u00e4ft erm\u00f6glichten. Daf\u00fcr werden die Journalisten Jan Jir\u00e1t, Kaspar Surber und Lorenz Naegeli mit dem Prix Transparence 2020 ausgezeichnet.<\/strong><\/p>\n<p>Noch nie haben Medienschaffende mit den \u00d6ffentlichkeitsgesetzen so viele Beitr\u00e4ge realisiert wie im vergangenen Corona-Krisen-Jahr. Mit Protokollen wurde belegt, wie die Beh\u00f6rden das Pandemie-Risiko anfangs untersch\u00e4tzten, oder dann konnte das Masken-Debakel nachgezeichnet werden. Zur besten Transparenzstory des Jahres 2020 k\u00fcrte eine <a href=\"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/jury-prix-transparence-2019\/\">ChefredaktorInnen-Jury<\/a> schliesslich einen \u00abWOZ\u00bb-Beitrag zu Waffenexporten.\u00a0<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>\u00abDie Wochenzeitung\u00bb musste sich die Daten zum Schweizer R\u00fcstungsgesch\u00e4ft hartn\u00e4ckig erstreiten. Das Staatssekretariat f\u00fcr Wirtschaft (Seco) verweigerte den Zugang zur Firmenliste, da Gesch\u00e4ftsgeheimnisse und aussenpolitischen Interessen der Schweiz tangiert seien. In einem unmissverst\u00e4ndlichen Urteil machte das Bundesgericht dann aber klar, dass die Namen der R\u00fcstungsexport-Firmen ver\u00f6ffentlicht werden m\u00fcssen.<\/p>\n<p><strong>Schweiz ist Teil eines globalisierten Waffengesch\u00e4fts<\/strong><\/p>\n<p>Die von den \u00abWOZ\u00bb-Journalisten erk\u00e4mpften Daten geben erstmals einen tiefen Einblick ins Schweizer Waffengesch\u00e4ft: Sie zeigen, wer die rund 150 im R\u00fcstungsgesch\u00e4ft t\u00e4tigen Firmen sind, welche vom Bund 2017 eine Exportbewilligung erhalten haben. \u00abDas Gesch\u00e4ft hat jetzt Name und Adresse\u00bb, sagt \u00abWOZ\u00bb-Co-Redaktionsleiter Kaspar Surber.<\/p>\n<div class=\"infobox\"><\/p>\n<p><strong>Die Preistr\u00e4ger des Prix Transparence<\/strong><\/p>\n<p><em>\u00d6ffentlichkeitsgesetz.ch<\/em>\u00a0verleiht den Prix Transparence zum dritten Mal. Damit ausgezeichnet werden Medienschaffende, welche ein \u00d6ffentlichkeitsgesetz zielf\u00fchrend und wirkungsvoll anwenden.<\/p>\n<p><div class=\"infobox-more\"><button class=\"info-plus\" type=\"button\"><\/button><div class=\"infobox-inner\"><\/p>\n<p>Ein Pokal, der vom Berner Kunstglaser Daniel Stettler aus Berner Amtshaus-Sandstein und Glas geschaffen worden ist, wurde der \u00abWOZ\u00bb-Redaktion in Z\u00fcrich \u00fcbergeben.<\/p>\n<ul>\n<li>2019 wurden <a href=\"https:\/\/www.youtube.com\/watch?v=4xzxLqn5QTU&amp;feature=emb_logo\">Nina Blaser und Anielle Peterhans (\u00abRundschau\u00bb)<\/a> ausgezeichnet. Sie brachten die Fakten \u00fcber die Preisverhandlungen zu einem Krebsmedikament auf den Tisch.<\/li>\n<li>2018 wurde <a href=\"https:\/\/www.youtube.com\/watch?v=M63mge87OTU&amp;feature=emb_logo\">Philippe Boeglin (\u00abLa Libert\u00e9\u00bb)<\/a> geehrt. Er enth\u00fcllte mithilfe des \u00d6ffentlichkeitsgesetzes Spesenexzesse der Armee.<br \/>\n<\/div><\/div><\/li>\n<\/ul>\n<p><\/div>\n<p>&nbsp;<\/p>\n<p>Die Daten belegen, dass die Schweizer R\u00fcstungsfirmen l\u00e4ngst Teil eines globalisierten Waffenhandelsgesch\u00e4fts sind, in dem ein Dutzend Konzerne den Ton angeben. Die in Debatten immer wieder vorgebrachte Behauptung, KMUs seien das R\u00fcckgrat der Schweizer R\u00fcstungsindustrie, sei entkr\u00e4ftet worden, schreibt die \u00abWOZ\u00bb. Schweizer KMUs tauchen in den im Sommer 2020 publik gemachten Daten als Lieferanten von Stanzmaschinen, ABC-Filtern oder optischen Ger\u00e4ten auf.<\/p>\n<p><strong>Ausdauer und Hartn\u00e4ckigkeit beeindruckten die Jury<\/strong><\/p>\n<p>Die erstrittenen Daten von R\u00fcstungskonzernen, Zulieferern und Waffenh\u00e4ndlern hat die \u00abWOZ\u00bb in einer interaktiven Karte aufbereitet. Das Seco, welches die Publikation der Informationen bis zuletzt verhindern wollte, verlangte von der Zeitung f\u00fcr deren Bereitstellung 5458 Franken.<\/p>\n<p><div class=\"embed-responsive embed-responsive-16by9\"><div class=\"iframe-container\"><iframe loading=\"lazy\" class=\"embed-responsive-item\"  title=\"Prix Transparence 2020 - \u00d6ffentlichkeitsgesetz.ch\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9F9IwjtLJvc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/div>\n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abDiese Recherche erm\u00f6glicht ein klareres Bild \u00fcber die Unternehmen, die im Schweizer R\u00fcstungsgesch\u00e4ft aktiv sind\u00bb, sagt Jury-Mitglied Serge Gumy. Der Chefredaktor von \u00abLa Libert\u00e9\u00bb zeigt sich beeindruckt von der Ausdauer und der Hartn\u00e4ckigkeit, welche die Journalisten gezeigt haben, um an die Dokumente zu gelangen. In der heiklen Debatte um Waffenexporte beleuchte die journalistische Arbeit das Thema aus einem anderen Blickwinkel: \u00abDas ist von \u00f6ffentlichem Interesse\u00bb, sagt er. Die Recherche sei ein grosser Schritt \u00absowohl f\u00fcr den Journalismus als auch f\u00fcr die Transparenz gegen\u00fcber der Bev\u00f6lkerung\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lonza und Pestizid-Verschmutzung auf Platz zwei und drei<\/strong><\/p>\n<p>Mit dem zweiten Platz geehrt wird der Beitrag \u00abDie Klimaschande von Visp\u00bb von \u00abTamedia\u00bb-Journalist Christoph Lenz. Mithilfe von herausverlangten E-Mails belegt er im \u00abMagazin\u00bb ein gravierendes Umweltversagen des Lonza-Werks im Wallis und der Beh\u00f6rden. Ausgangspunkt seiner Recherche war die Mitteilung, dass das Chemiewerk ein Prozent der Treibhausgase der Schweiz ausst\u00f6sst.<\/p>\n<p>Die beiden Journalisten Mathias Gottet und Cedric Fr\u00f6hlich wurden f\u00fcr ihren Beitrag \u00abDas dreckige Wasserschloss\u00bb zu Pestizid-Verschmutzungen im Kanton Bern mit dem dritten Platz ausgezeichnet. Der in der \u00abBerner Zeitung\u00bb erschienene Beitrag enth\u00fcllt mithilfe des Berner Informationsgesetzes, dass in viel mehr Trinkwasserfassungen als bisher angenommen Chlorothalonil gefunden worden ist.<\/p>\n<p>Insgesamt hat <em>\u00d6ffentlichkeitsgesetz.ch<\/em> 106 Beitr\u00e4ge aus Presse, Rundfunk und TV evaluiert, welche 2020 mithilfe eines \u00d6ffentlichkeitsgesetzes realisiert worden sind. <a href=\"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/2020\/12\/das-sind-die-nominierten-fur-den-prix-transparence-2020\/\">Zehn davon<\/a> wurden f\u00fcr den Prix Transparence 2020 nominiert.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Martin Stoll. F\u00fcnf Jahre lang k\u00e4mpften sie f\u00fcr die Daten, die schliesslich einen tiefen Einblick ins Schweizer R\u00fcstungsgesch\u00e4ft erm\u00f6glichten. Daf\u00fcr werden die Journalisten Jan Jir\u00e1t, Kaspar Surber und Lorenz Naegeli mit dem Prix Transparence 2020 ausgezeichnet. Noch nie haben Medienschaffende mit den \u00d6ffentlichkeitsgesetzen so viele Beitr\u00e4ge realisiert wie im vergangenen Corona-Krisen-Jahr. Mit Protokollen wurde [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[188,69],"class_list":["post-12856","post","type-post","status-publish","format-standard","hentry","category-bundesverwaltung","tag-prix-transparence","tag-seco"],"_links":{"self":[{"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/posts\/12856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/comments?post=12856"}],"version-history":[{"count":5,"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/posts\/12856\/revisions"}],"predecessor-version":[{"id":12919,"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/posts\/12856\/revisions\/12919"}],"wp:attachment":[{"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/media?parent=12856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/categories?post=12856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oeffentlichkeitsgesetz.ch\/deutsch\/wp-json\/wp\/v2\/tags?post=12856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}